{"id":48497,"date":"2026-05-12T10:19:52","date_gmt":"2026-05-12T08:19:52","guid":{"rendered":"https:\/\/mercia-academy.ch\/?post_type=courses&#038;p=48497"},"modified":"2026-05-12T09:19:56","modified_gmt":"2026-05-12T08:19:56","slug":"arkedance-en-madrid-la-danza-meditativa-de-los-arquetipos-mayores-1a-parte-del-1er-modulo","status":"publish","type":"courses","link":"https:\/\/mercia-academy.ch\/en\/cursos\/arkedance-en-madrid-la-danza-meditativa-de-los-arquetipos-mayores-1a-parte-del-1er-modulo\/","title":{"rendered":"Ark\u00e9dance en Madrid &#8211; \u00abLa Danza Meditativa de los Arquetipos Mayores\u00bb (1a parte del 1er M\u00f3dulo)"},"content":{"rendered":"<p><strong>MADRID<\/strong>\u00a0&#8211; Presencial con <strong>Sandra Rodr\u00edguez<\/strong><\/p>\n<p>S\u00e1bado 20 Junio\u00a0 de 10.00h a 12.30 y de 16.30h a 19.30h<\/p>\n<p>Casa Rural \u00abLos Casta\u00f1os\u00bb &#8211; 655 197 043 &#8211; soplodevida22@yahoo.es<\/p>\n<p><span style=\"text-decoration: underline\">PROGRAMA:<\/span><\/p>\n<p>*<strong>Comprensi\u00f3n<\/strong> del <strong>Ark\u00e9dance:\u00a0 \u00a0<\/strong>Ubicaci\u00f3n de los continentes en el espacio, la remontada, los sentidos , los sonidos, los arrquetipos mayores, la m\u00fasica, el centro de la rosa.<\/p>\n<p>*El arquetipo mayor de <strong>\u00c1frica<\/strong>, El <strong>\u00c1guila, <\/strong>\u00a0con el elemento <strong>Fuego <\/strong>y en relaci\u00f3n al\u00a0<strong>\u00a0 \u00a0 \u00a0 Sentido de la Vista.<\/strong><\/p>\n<p style=\"text-align: center\"><em><strong>\u00abLa Mirada que tenemos sobre nosotr@s mism@s , sobre l@s dem\u00e1s, sobre las situaciones&#8230;\u00bb<\/strong><\/em><\/p>\n<p>*El arquetipo mayor de <strong>Am\u00e9rica<\/strong>, el <strong>Le\u00f3n<\/strong>, en correspondencia con el <strong>Elemento Aire <\/strong>y en relaci\u00f3n con el <strong>Sentido del Olfato.<\/strong><\/p>\n<p style=\"text-align: center\"><strong><em>\u00abNos permite , con su poder pac\u00edfico controlar los estados de \u00e1nimo y los sentimientos agresivos\u00bb<\/em><\/strong><\/p>\n<p>*El arquetipo mayor de <strong>Asia <\/strong>es <strong>Sonido Primordial<\/strong>\u00a0, en correspondencia con el <strong>Elemento Agua <\/strong>y en relaci\u00f3n con el <strong>Sentido del O\u00eddo.<\/strong><\/p>\n<p style=\"text-align: center\"><strong><em>\u00abEscuchar y ser escuchados\u00bb<\/em><\/strong><\/p>\n<p><strong>Ark\u00e9dance<\/strong> invita\u00a0 a adentrarnos en lo m\u00e1s profundo y as\u00ed conectar con nuestro sentido de pertenencia al Todo.<\/p>\n<p>La m\u00fasica, est\u00e1 exquisitamente seleccionada y testada por la autora de esta maravillosa ense\u00f1anza <em><strong>Daniel Didier,<\/strong><\/em> as\u00ed como los sonidos universales, y cada uno de los \u00abgestos\u00bb del Ark\u00e9dance.<\/p>\n<p>El \u00c1guila, El\u00a0 Le\u00f3n y el Sonido Primordial son\u00a0 los tres primeros arquetipos mayores, que nos acompa\u00f1ar\u00e1n en este\u00a0 \u00abviaje\u00bb de Baile, m\u00fasica, sonidos&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID\u00a0&#8211; Presencial con Sandra Rodr\u00edguez S\u00e1bado 20 Junio\u00a0 de 10.00h a 12.30 y de 16.30h a 19.30h Casa<\/p>\n","protected":false},"author":414,"featured_media":47867,"template":"","course-category":[160,253,281,161,255,361,165,153],"course-tag":[],"class_list":["post-48497","courses","type-courses","status-publish","has-post-thumbnail","hentry","course-category-arkedance","course-category-arkedanza","course-category-cursos-presenciales","course-category-dance-of-the-archetypes","course-category-danza-de-los-arquetipos","course-category-espanol","course-category-face-to-face-courses","course-category-spanish"],"_links":{"self":[{"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/courses\/48497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/types\/courses"}],"author":[{"embeddable":true,"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/users\/414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/media\/47867"}],"wp:attachment":[{"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/media?parent=48497"}],"wp:term":[{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/course-category?post=48497"},{"taxonomy":"course-tag","embeddable":true,"href":"https:\/\/mercia-academy.ch\/es\/wp-json\/wp\/v2\/course-tag?post=48497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}